{"id":1772,"date":"2023-11-16T14:42:13","date_gmt":"2023-11-16T13:42:13","guid":{"rendered":"https:\/\/berghaus-wengen.ch\/aktivitaten\/escalade\/"},"modified":"2025-11-05T10:53:26","modified_gmt":"2025-11-05T09:53:26","slug":"escalade","status":"publish","type":"aktivitaten","link":"https:\/\/berghaus-wengen.ch\/fr\/aktivitaten\/escalade\/","title":{"rendered":"Escalade"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Mouvement dans la verticale\u2026<\/p>\n\n<p class=\"wp-block-paragraph\">La face nord de l\u2019Eiger de renomm\u00e9e mondiale et notoire est probablement la quintessence des d\u00e9fis d\u2019escalade alpine. Mais ce n\u2019est qu\u2019un c\u00f4t\u00e9 du large \u00e9ventail de possibilit\u00e9s pour se d\u00e9fouler \u00e0 la verticale.<\/p>\n\n<p class=\"wp-block-paragraph\">Il existe \u00e9galement diverses possibilit\u00e9s pour les amateurs de via ferrata dans l\u2019Oberland bernois.<\/p>\n\n<p class=\"wp-block-paragraph\">Que diriez-vous de la via <a href=\"http:\/\/www.klettersteig-muerren.ch\/index.php\/de\/\" target=\"_blank\" rel=\"noreferrer noopener\">ferrata de M\u00fcrren Gimmelwald<\/a> par exemple ?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mouvement dans la verticale\u2026<\/p>\n","protected":false},"featured_media":2266,"template":"","kategorien-aktivitaten":[57],"season":[],"class_list":["post-1772","aktivitaten","type-aktivitaten","status-publish","has-post-thumbnail","hentry","kategorien-aktivitaten-sommer"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Escalade - Hotel Berghaus Wengen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/berghaus-wengen.ch\/fr\/aktivitaten\/escalade\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Escalade - Hotel Berghaus Wengen\" \/>\n<meta property=\"og:description\" content=\"Mouvement dans la verticale\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/berghaus-wengen.ch\/fr\/aktivitaten\/escalade\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Berghaus Wengen\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-05T09:53:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/berghaus-wengen.ch\/wp-content\/uploads\/2023\/11\/Via-Ferrata.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/berghaus-wengen.ch\\\/fr\\\/aktivitaten\\\/escalade\\\/\",\"url\":\"https:\\\/\\\/berghaus-wengen.ch\\\/fr\\\/aktivitaten\\\/escalade\\\/\",\"name\":\"Escalade - Hotel Berghaus Wengen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/berghaus-wengen.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/berghaus-wengen.ch\\\/fr\\\/aktivitaten\\\/escalade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/berghaus-wengen.ch\\\/fr\\\/aktivitaten\\\/escalade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/berghaus-wengen.ch\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Via-Ferrata.jpg\",\"datePublished\":\"2023-11-16T13:42:13+00:00\",\"dateModified\":\"2025-11-05T09:53:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/berghaus-wengen.ch\\\/fr\\\/aktivitaten\\\/escalade\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/berghaus-wengen.ch\\\/fr\\\/aktivitaten\\\/escalade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/berghaus-wengen.ch\\\/fr\\\/aktivitaten\\\/escalade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/berghaus-wengen.ch\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Via-Ferrata.jpg\",\"contentUrl\":\"https:\\\/\\\/berghaus-wengen.ch\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Via-Ferrata.jpg\",\"width\":1000,\"height\":750,\"caption\":\"KONICA MINOLTA DIGITAL CAMERA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/berghaus-wengen.ch\\\/fr\\\/aktivitaten\\\/escalade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/berghaus-wengen.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Escalade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/berghaus-wengen.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/berghaus-wengen.ch\\\/fr\\\/\",\"name\":\"Hotel Berghaus Wengen\",\"description\":\"Herzlich willkommen im Berghaus \u2013 dem gem\u00fctlichen Hotel in der Jungfrauregion!\",\"publisher\":{\"@id\":\"https:\\\/\\\/berghaus-wengen.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/berghaus-wengen.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/berghaus-wengen.ch\\\/fr\\\/#organization\",\"name\":\"Hotel Berghaus Wengen\",\"url\":\"https:\\\/\\\/berghaus-wengen.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/berghaus-wengen.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/berghaus-wengen.ch\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-logo-berghaus-1-1.png\",\"contentUrl\":\"https:\\\/\\\/berghaus-wengen.ch\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-logo-berghaus-1-1.png\",\"width\":387,\"height\":133,\"caption\":\"Hotel Berghaus Wengen\"},\"image\":{\"@id\":\"https:\\\/\\\/berghaus-wengen.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Escalade - Hotel Berghaus Wengen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/berghaus-wengen.ch\/fr\/aktivitaten\/escalade\/","og_locale":"fr_FR","og_type":"article","og_title":"Escalade - Hotel Berghaus Wengen","og_description":"Mouvement dans la verticale\u2026","og_url":"https:\/\/berghaus-wengen.ch\/fr\/aktivitaten\/escalade\/","og_site_name":"Hotel Berghaus Wengen","article_modified_time":"2025-11-05T09:53:26+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/berghaus-wengen.ch\/wp-content\/uploads\/2023\/11\/Via-Ferrata.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/berghaus-wengen.ch\/fr\/aktivitaten\/escalade\/","url":"https:\/\/berghaus-wengen.ch\/fr\/aktivitaten\/escalade\/","name":"Escalade - Hotel Berghaus Wengen","isPartOf":{"@id":"https:\/\/berghaus-wengen.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/berghaus-wengen.ch\/fr\/aktivitaten\/escalade\/#primaryimage"},"image":{"@id":"https:\/\/berghaus-wengen.ch\/fr\/aktivitaten\/escalade\/#primaryimage"},"thumbnailUrl":"https:\/\/berghaus-wengen.ch\/wp-content\/uploads\/2023\/11\/Via-Ferrata.jpg","datePublished":"2023-11-16T13:42:13+00:00","dateModified":"2025-11-05T09:53:26+00:00","breadcrumb":{"@id":"https:\/\/berghaus-wengen.ch\/fr\/aktivitaten\/escalade\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/berghaus-wengen.ch\/fr\/aktivitaten\/escalade\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/berghaus-wengen.ch\/fr\/aktivitaten\/escalade\/#primaryimage","url":"https:\/\/berghaus-wengen.ch\/wp-content\/uploads\/2023\/11\/Via-Ferrata.jpg","contentUrl":"https:\/\/berghaus-wengen.ch\/wp-content\/uploads\/2023\/11\/Via-Ferrata.jpg","width":1000,"height":750,"caption":"KONICA MINOLTA DIGITAL CAMERA"},{"@type":"BreadcrumbList","@id":"https:\/\/berghaus-wengen.ch\/fr\/aktivitaten\/escalade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/berghaus-wengen.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Escalade"}]},{"@type":"WebSite","@id":"https:\/\/berghaus-wengen.ch\/fr\/#website","url":"https:\/\/berghaus-wengen.ch\/fr\/","name":"Hotel Berghaus Wengen","description":"Herzlich willkommen im Berghaus \u2013 dem gem\u00fctlichen Hotel in der Jungfrauregion!","publisher":{"@id":"https:\/\/berghaus-wengen.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/berghaus-wengen.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/berghaus-wengen.ch\/fr\/#organization","name":"Hotel Berghaus Wengen","url":"https:\/\/berghaus-wengen.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/berghaus-wengen.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/berghaus-wengen.ch\/wp-content\/uploads\/2023\/11\/cropped-logo-berghaus-1-1.png","contentUrl":"https:\/\/berghaus-wengen.ch\/wp-content\/uploads\/2023\/11\/cropped-logo-berghaus-1-1.png","width":387,"height":133,"caption":"Hotel Berghaus Wengen"},"image":{"@id":"https:\/\/berghaus-wengen.ch\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/berghaus-wengen.ch\/fr\/wp-json\/wp\/v2\/aktivitaten\/1772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berghaus-wengen.ch\/fr\/wp-json\/wp\/v2\/aktivitaten"}],"about":[{"href":"https:\/\/berghaus-wengen.ch\/fr\/wp-json\/wp\/v2\/types\/aktivitaten"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/berghaus-wengen.ch\/fr\/wp-json\/wp\/v2\/media\/2266"}],"wp:attachment":[{"href":"https:\/\/berghaus-wengen.ch\/fr\/wp-json\/wp\/v2\/media?parent=1772"}],"wp:term":[{"taxonomy":"kategorien-aktivitaten","embeddable":true,"href":"https:\/\/berghaus-wengen.ch\/fr\/wp-json\/wp\/v2\/kategorien-aktivitaten?post=1772"},{"taxonomy":"season","embeddable":true,"href":"https:\/\/berghaus-wengen.ch\/fr\/wp-json\/wp\/v2\/season?post=1772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}